{"id":4502,"date":"2024-02-06T22:05:44","date_gmt":"2024-02-06T22:05:44","guid":{"rendered":"http:\/\/www.montanhismo-guarda.pt\/portal\/?post_type=tribe_events&#038;p=4502"},"modified":"2024-03-15T23:53:07","modified_gmt":"2024-03-15T23:53:07","slug":"marcha-regional-marco-2024","status":"publish","type":"tribe_events","link":"https:\/\/www.montanhismo-guarda.pt\/portal\/evento\/marcha-regional-marco-2024","title":{"rendered":"Marcha Regional &#8211; Mar\u00e7o 2024"},"content":{"rendered":"<div  class=\"tribe-events-schedule tribe-clearfix\" >\n\t<p class=\"tribe-events-schedule__datetime\">\n\t\t<span class=\"tribe-events-schedule__date tribe-events-schedule__date--start\">\n\t\t\t23 de Mar\u00e7o de 2024\t\t<\/span>\n\n\t\t\t\t\t<span class=\"tribe-events-schedule__all-day\">Todo o dia<\/span>\n\t\t\n\t\t\t<\/p>\n<\/div>\n\n\n<figure class=\"aligncenter wp-block-post-featured-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"1080\" src=\"https:\/\/www.montanhismo-guarda.pt\/portal\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-03-08-at-15.44.38.jpeg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" style=\"object-fit:cover;\" srcset=\"https:\/\/www.montanhismo-guarda.pt\/portal\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-03-08-at-15.44.38.jpeg 1080w, https:\/\/www.montanhismo-guarda.pt\/portal\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-03-08-at-15.44.38-300x300.jpeg 300w, https:\/\/www.montanhismo-guarda.pt\/portal\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-03-08-at-15.44.38-1024x1024.jpeg 1024w, https:\/\/www.montanhismo-guarda.pt\/portal\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-03-08-at-15.44.38-150x150.jpeg 150w, https:\/\/www.montanhismo-guarda.pt\/portal\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-03-08-at-15.44.38-768x768.jpeg 768w, https:\/\/www.montanhismo-guarda.pt\/portal\/wp-content\/uploads\/2024\/02\/WhatsApp-Image-2024-03-08-at-15.44.38-100x100.jpeg 100w\" sizes=\"auto, 100vw\" \/><\/figure>\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&#8220;Cabe\u00e7o das Fr\u00e1guas \u00e9 um dos lugares m\u00edticos de Portugal&#8221;<\/p>\n<\/blockquote>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Programa<\/h2>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td><strong>Dia_23<br>8:00<\/strong><\/td><td><a href=\"https:\/\/osm.org\/go\/b8niD2on?m=\" target=\"_blank\" rel=\"noreferrer noopener\">In\u00edcio da caminhada desde o campo de futebol de Benespera.<\/a><br>Percurso <strong>linear<\/strong>:<br><strong>\u2248 14 kms<\/strong> de dist\u00e2ncia<br><strong>Algo dif\u00edcil<\/strong><\/td><\/tr><tr><td><strong>8:30<\/strong><\/td><td><a href=\"https:\/\/osm.org\/go\/b8niIf2v?m=\" target=\"_blank\" rel=\"noreferrer noopener\">In\u00edcio da caminhada desde a Esta\u00e7\u00e3o Ferrovi\u00e1ria de Benespera.<\/a><br>Percurso <strong>linear<\/strong>:<br><strong>\u2248 12 kms<\/strong> de dist\u00e2ncia<br><strong>Algo dif\u00edcil<\/strong><\/td><\/tr><tr><td><strong><strong><strong><strong><strong>\u22481<\/strong><\/strong><\/strong><\/strong>0:30<\/strong><\/td><td>(assim que chegarem os restantes caminheiros)<br><a href=\"https:\/\/osm.org\/go\/b8m32FPH?m=\" target=\"_blank\" rel=\"noreferrer noopener\">In\u00edcio da caminhada desde a Quinta de Besteiros.<\/a><br>Percurso <strong>linear<\/strong>:<br><strong>\u2248 8 kms<\/strong> de dist\u00e2ncia<br><strong>Algo dif\u00edcil<\/strong><\/td><\/tr><tr><td><strong><strong><strong><strong>~:~<\/strong><\/strong><\/strong><\/strong><\/td><td>Fim da marcha e in\u00edcio do pic-nic<\/td><\/tr><tr><td><strong><strong><strong><strong>~:~<\/strong><\/strong><\/strong><\/strong><\/td><td>Regresso <a href=\"#regresso\">[ver Regresso]<\/a><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"transporte\">Percurso<\/h4>\n\n\n\n<p>O percurso ser\u00e1 acompanhado pelos arque\u00f3logos Ricardo Fidalgo e Tiago Ramos e ocorrer\u00e1 uma interpreta\u00e7\u00e3o do patrim\u00f3nio pela Associa\u00e7\u00e3o Hereditas.<\/p>\n\n\n\n<p>De seguida descemos\u00a0at\u00e9 \u00e0 Quinta de Besteiros onde faremos o habitual pic-nic\/farnel &#8211; &#8220;<em>tr\u00e1s o Teu e come do de todos<\/em>&#8220;. (os &#8220;farn\u00e9is&#8221; ser\u00e3o transportados numa viatura)<\/p>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"regresso\">Regresso<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>4 Km at\u00e9 Esta\u00e7\u00e3o Ferrovi\u00e1ria de Benespera;<\/li>\n\n\n\n<li>6 Km at\u00e9 ao campo de futebol de Benespera.<\/li>\n<\/ul>\n\n\n\n<p>Existe disponibilidade de transporte para quem n\u00e3o regressar a caminhar.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Chegada e partida de comboio<\/h4>\n\n\n\n<p>Para quem quiser, tem a oportunidade de ir e regressar de comboio:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Saindo da esta\u00e7\u00e3o da Guarda, \n<ul class=\"wp-block-list\">\n<li>poder\u00e1 apanhar o Intercidades 540 que chegar\u00e1 \u00e0 esta\u00e7\u00e3o da Benespera \u00e0s 07:16;<\/li>\n\n\n\n<li>no regresso, poder\u00e1 apanhar o Intercidades 543, pelas 17:26.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<h2 class=\"wp-block-heading\">Inscri\u00e7\u00e3o<\/h2>\n\n\n\n<p>As <a href=\"#inscrever\">inscri\u00e7\u00f5es ser\u00e3o aceites at\u00e9 dia <strong>20 de mar\u00e7o<\/strong>, atrav\u00e9s do <strong>formul\u00e1rio<\/strong> a que pode aceder mais abaixo.<\/a><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Comparticipa\u00e7\u00e3o log\u00edstica<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>3\u20ac<\/strong><\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Observa\u00e7\u00f5es<\/h4>\n\n\n\n<p>Os companheiros que n\u00e3o sejam possuidores de seguro de acidentes pessoais, e pretendam que seja o clube a tratar disso, devem comunic\u00e1-lo no ato da inscri\u00e7\u00e3o (preenchimento completo do formul\u00e1rio de inscri\u00e7\u00e3o), indicando o NIF, BI\/CC, data de&nbsp;nascimento e contacto telef\u00f3nico.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Respons\u00e1veis pela Actividade<\/h4>\n\n\n\n<p><a href=\"tel:+351966907837\" target=\"_blank\" rel=\"noreferrer noopener\">Deolinda Pina (966 907 837)<\/a> <sub>Chamada para rede m\u00f3vel nacional<\/sub><\/p>\n\n\n\n<p><a rel=\"noreferrer noopener\" href=\"tel:+351966478807\" target=\"_blank\">Jo\u00e3o&nbsp;Gon\u00e7alves (966 478 807)<\/a> <sub>Chamada para rede m\u00f3vel nacional<\/sub><\/p>\n\n\n\n<p><a href=\"tel:+351967853399\" target=\"_blank\" rel=\"noreferrer noopener\">S\u00e9rgio Pissarra (967 853 399)<\/a> <sub>Chamada para rede m\u00f3vel nacional<\/sub><\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Organiza\u00e7\u00e3o<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Associa\u00e7\u00e3o Cultural e Recreativa de Benespera<\/li>\n\n\n\n<li>Associa\u00e7\u00e3o Move Beiras<\/li>\n\n\n\n<li>Clube de Cicloturismo da Vela<\/li>\n\n\n\n<li>Clube de Montanhismo da Guarda<\/li>\n\n\n\n<li>Guarda Runners<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-16018d1d wp-block-buttons-is-layout-flex\" id=\"inscrever\">\n<div class=\"wp-block-button is-style-outline is-style-outline--1\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/forms.gle\/Na1qZdFr9PGzQdKDA\" target=\"_blank\" rel=\"noreferrer noopener\">Inscrever<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&#8220;O Cabe\u00e7o das Fr\u00e1guas junta tudo: religi\u00e3o, lendas, arqueologia, hist\u00f3ria e, at\u00e9, uma das raras inscri\u00e7\u00f5es em l\u00edngua lusitana com caracteres latinos.&#8221;<\/p>\n<cite>viagens.sapo.pt<\/cite><\/blockquote>\n\n\n<div  class=\"tribe-block tribe-block__event-price\" >\n\t\t<\/div>\n\n\n\n\n<div  class=\"tribe-block tribe-block__venue tribe-clearfix tribe-block__venue--has-map\" >\n\t\n\t\t\n\t<\/div>\n\n\n\n\n\t<div  class=\"tribe-block tribe-block__events-link\" >\n\t\t<div class=\"tribe-events tribe-common\">\n\t\t\t<div class=\"tribe-events-c-subscribe-dropdown__container\">\n\t\t\t\t<div class=\"tribe-events-c-subscribe-dropdown\">\n\t\t\t\t\t<div class=\"tribe-common-c-btn-border tribe-events-c-subscribe-dropdown__button\">\n\t\t\t\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--cal-export tribe-events-c-subscribe-dropdown__export-icon\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 23 17\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M.128.896V16.13c0 .211.145.383.323.383h15.354c.179 0 .323-.172.323-.383V.896c0-.212-.144-.383-.323-.383H.451C.273.513.128.684.128.896Zm16 6.742h-.901V4.679H1.009v10.729h14.218v-3.336h.901V7.638ZM1.01 1.614h14.218v2.058H1.009V1.614Z\" \/>\n\t<path d=\"M20.5 9.846H8.312M18.524 6.953l2.89 2.909-2.855 2.855\" stroke-width=\"1.2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"\/>\n<\/svg>\n\t\t\t\t\t\t<button\n\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__button-text\"\n\t\t\t\t\t\t\taria-expanded=\"false\"\n\t\t\t\t\t\t\taria-controls=\"tribe-events-subscribe-dropdown-content\"\n\t\t\t\t\t\t\taria-label=\"View links to add events to your calendar\"\n\t\t\t\t\t\t>\n\t\t\t\t\t\t\tAdicionar ao calend\u00e1rio\t\t\t\t\t\t<\/button>\n\t\t\t\t\t\t<svg\n\t class=\"tribe-common-c-svgicon tribe-common-c-svgicon--caret-down tribe-events-c-subscribe-dropdown__button-icon\" \taria-hidden=\"true\"\n\tviewBox=\"0 0 10 7\"\n\txmlns=\"http:\/\/www.w3.org\/2000\/svg\"\n>\n\t<path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M1.008.609L5 4.6 8.992.61l.958.958L5 6.517.05 1.566l.958-.958z\" class=\"tribe-common-c-svgicon__svg-fill\"\/>\n<\/svg>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"tribe-events-subscribe-dropdown-content\" class=\"tribe-events-c-subscribe-dropdown__content\">\n\t\t\t\t\t\t<ul class=\"tribe-events-c-subscribe-dropdown__list\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--gcal\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"https:\/\/www.google.com\/calendar\/event?action=TEMPLATE&#038;dates=20240323T000000\/20240323T235959&#038;text=Marcha%20Regional%20%26%238211%3B%20Mar%C3%A7o%202024&#038;details=%3Cblockquote+class%3D%22wp-block-quote%22%3E%3Cp%3E%22Cabe%C3%A7o+das+Fr%C3%A1guas+%C3%A9+um+dos+lugares+m%C3%ADticos+de+Portugal%22%3C%2Fp%3E+%3C%2Fblockquote%3E%3Cdiv+class%3D%22wp-block-columns%22%3E%3Cdiv+class%3D%22wp-block-column%22%3E%3Ch2+class%3D%22wp-block-heading%22%3EPrograma%3C%2Fh2%3E%3Cfigure+class%3D%22wp-block-table+is-style-stripes%22%3E%3Ctable%3E%3Ctbody%3E%3Ctr%3E%3Ctd%3E%3Cstrong%3EDia_23%3Cbr+%2F%3E8%3A00%3C%2Fstrong%3E%3C%2Ftd%3E%3Ctd%3E%3Ca+href%3D%22https%3A%2F%2Fosm.org%2Fgo%2Fb8niD2on%3Fm%3D%22+target%3D%22_blank%22+rel%3D%22noreferrer+noopener%22%3EIn%C3%ADcio+da+caminhada+desde+o+campo+de+futebol+de+Benespera.%3C%2Fa%3E%3Cbr+%2F%3EPercurso+%3Cstrong%3Elinear%3C%2Fstrong%3E%3A%3Cbr+%2F%3E%3Cstrong%3E%E2%89%88+14+kms%3C%2Fstrong%3E+de+dist%C3%A2ncia%3Cbr+%2F%3E%3Cstrong%3EAlgo+dif%C3%ADcil%3C%2Fstrong%3E%3C%2Ftd%3E%3C%2Ftr%3E%3Ctr%3E%3Ctd%3E%3Cstrong%3E8%3A30%3C%2Fstrong%3E%3C%2Ftd%3E%3Ctd%3E%3Ca+href%3D%22https%3A%2F%2Fosm.org%2Fgo%2Fb8niIf2v%3Fm%3D%22+target%3D%22_blank%22+rel%3D%22noreferrer+noopener%22%3EIn%C3%ADcio+da+caminhada+desde+a+Esta%C3%A7%C3%A3o+Ferrovi%C3%A1ria+de+Benespera.%3C%2Fa%3E%3Cbr+%2F%3EPercurso+%3Cstrong%3Elinear%3C%2Fstrong%3E%3A%3Cbr+%2F%3E%3Cstrong%3E%E2%89%88+12+kms%3C%2Fstrong%3E+de+dist%C3%A2ncia%3Cbr+%2F%3E%3Cstrong%3EAlgo+dif%C3%ADcil%3C%2Fstrong%3E%3C%2Ftd%3E%3C%2Ftr%3E%3Ctr%3E%3Ctd%3E%3Cstrong%3E%3C%2Fstrong%3E%3Cstrong%3E%3C%2Fstrong%3E%3Cstrong%3E%3C%2Fstrong%3E%3Cstrong%3E%3C%2Fstrong%3E%3Cstrong%3E%E2%89%881%3C%2Fstrong%3E%3C%2F%3C%2Ftd%3E%3C%2Ftr%3E%3C%2Ftbody%3E%3C%2Ftable%3E%3C%2Ffigure%3E%3C%2Fdiv%3E%3C%2Fdiv%3E+%28Veja+a+descri%C3%A7%C3%A3o+completa+de+evento+aqui%3A+https%3A%2F%2Fwww.montanhismo-guarda.pt%2Fportal%2Fevento%2Fmarcha-regional-marco-2024%29&#038;trp=false&#038;ctz=Europe\/Lisbon&#038;sprop=website:https:\/\/www.montanhismo-guarda.pt\/portal\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tCalend\u00e1rio Google\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--ical\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tiCalendar\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-365\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tOutlook 365\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li class=\"tribe-events-c-subscribe-dropdown__list-item tribe-events-c-subscribe-dropdown__list-item--outlook-live\">\n\t\t\t\t\t\t\t\t\t<a\n\t\t\t\t\t\t\t\t\t\thref=\"\"\n\t\t\t\t\t\t\t\t\t\tclass=\"tribe-events-c-subscribe-dropdown__list-item-link\"\n\t\t\t\t\t\t\t\t\t\ttarget=\"_blank\"\n\t\t\t\t\t\t\t\t\t\trel=\"noopener noreferrer nofollow noindex\"\n\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\t\tOutlook Live\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\n\n\n<h2 class=\"tribe-block__related-events__title\">Related Events<\/h2>\n\n<ul  class=\"tribe-related-events tribe-clearfix\" >\n\t\t\t<li>\n\t\n<div class=\"tribe-related-events-thumbnail\">\n\t<a href=\"https:\/\/www.montanhismo-guarda.pt\/portal\/evento\/marcha-junho-2026\/\" class=\"url\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"760\" src=\"https:\/\/www.montanhismo-guarda.pt\/portal\/wp-content\/uploads\/2026\/01\/Cartaz-MarchaJulho2026-707x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a>\n<\/div>\n\t<div class=\"tribe-related-event-info\">\n\t<h3 class=\"tribe-related-events-title\">\n\t\t<a href=\"https:\/\/www.montanhismo-guarda.pt\/portal\/evento\/marcha-junho-2026\/\" class=\"tribe-event-url\" rel=\"bookmark\">\n\t\t\tNo Trilho Onde o Morto Matou o Vivo\t\t<\/a>\n\t<\/h3>\n\t<span class=\"tribe-event-date-start\">19 de Julho<\/span><\/div>\n<\/li>\n\t\t\t<li>\n\t\n<div class=\"tribe-related-events-thumbnail\">\n\t<a href=\"https:\/\/www.montanhismo-guarda.pt\/portal\/evento\/marcha-das-vindimas-2026\/\" class=\"url\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"760\" src=\"https:\/\/www.montanhismo-guarda.pt\/portal\/wp-content\/uploads\/2026\/01\/Cartaz-MarchaVindimas2026-707x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a>\n<\/div>\n\t<div class=\"tribe-related-event-info\">\n\t<h3 class=\"tribe-related-events-title\">\n\t\t<a href=\"https:\/\/www.montanhismo-guarda.pt\/portal\/evento\/marcha-das-vindimas-2026\/\" class=\"tribe-event-url\" rel=\"bookmark\">\n\t\t\tMarcha das Vindimas 2026\t\t<\/a>\n\t<\/h3>\n\t<span class=\"tribe-event-date-start\">20 de Setembro<\/span><\/div>\n<\/li>\n\t\t\t<li>\n\t\n<div class=\"tribe-related-events-thumbnail\">\n\t<a href=\"https:\/\/www.montanhismo-guarda.pt\/portal\/evento\/marcha-outubro-2026\/\" class=\"url\" rel=\"bookmark\" tabindex=\"-1\" aria-hidden=\"true\"><img loading=\"lazy\" decoding=\"async\" width=\"525\" height=\"760\" src=\"https:\/\/www.montanhismo-guarda.pt\/portal\/wp-content\/uploads\/2026\/01\/Cartaz-MarchaOutubro2026-707x1024.jpg\" class=\"attachment-large size-large wp-post-image\" alt=\"\" \/><\/a>\n<\/div>\n\t<div class=\"tribe-related-event-info\">\n\t<h3 class=\"tribe-related-events-title\">\n\t\t<a href=\"https:\/\/www.montanhismo-guarda.pt\/portal\/evento\/marcha-outubro-2026\/\" class=\"tribe-event-url\" rel=\"bookmark\">\n\t\t\tMarcha na Serra da Estrela\t\t<\/a>\n\t<\/h3>\n\t<span class=\"tribe-event-date-start\">25 de Outubro<\/span><\/div>\n<\/li>\n\t<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Cabe\u00e7o das Fr\u00e1guas \u00e9 um dos lugares m\u00edticos de Portugal&#8221; Programa Dia_238:00 In\u00edcio da caminhada desde o campo de futebol de Benespera.Percurso linear:\u2248 14 kms de dist\u00e2nciaAlgo dif\u00edcil 8:30 In\u00edcio &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.montanhismo-guarda.pt\/portal\/evento\/marcha-regional-marco-2024\" class=\"more-link\">Continuar a ler <span class=\"screen-reader-text\">&#8220;Marcha Regional &#8211; Mar\u00e7o 2024&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":4722,"template":"","meta":{"_acf_changed":false,"_tec_requires_first_save":false,"_EventAllDay":true,"_EventTimezone":"Europe\/Lisbon","_EventStartDate":"2024-03-23 00:00:00","_EventEndDate":"2024-03-23 23:59:59","_EventStartDateUTC":"2024-03-23 00:00:00","_EventEndDateUTC":"2024-03-23 23:59:59","_EventShowMap":true,"_EventShowMapLink":true,"_EventURL":"","_EventCost":"","_EventCostDescription":"","_EventCurrencySymbol":"\u20ac","_EventCurrencyCode":"USD","_EventCurrencyPosition":"suffix","_EventDateTimeSeparator":" \u00e0s ","_EventTimeRangeSeparator":" \u2014 ","_EventOrganizerID":[],"_EventVenueID":[0],"_OrganizerEmail":"","_OrganizerPhone":"","_OrganizerWebsite":"","_VenueAddress":"","_VenueCity":"","_VenueCountry":"","_VenueProvince":"","_VenueState":"","_VenueZip":"","_VenuePhone":"","_VenueURL":"","_VenueStateProvince":"","_VenueLat":"","_VenueLng":"","_VenueShowMap":false,"_VenueShowMapLink":false,"_tribe_blocks_recurrence_rules":"","_tribe_blocks_recurrence_description":"","_tribe_blocks_recurrence_exclusions":"","_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[93],"tribe_events_cat":[120],"class_list":["post-4502","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","tag-guarda","tribe_events_cat-pedestrianismo","cat_pedestrianismo"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.montanhismo-guarda.pt\/portal\/wp-json\/wp\/v2\/tribe_events\/4502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.montanhismo-guarda.pt\/portal\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.montanhismo-guarda.pt\/portal\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.montanhismo-guarda.pt\/portal\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":6,"href":"https:\/\/www.montanhismo-guarda.pt\/portal\/wp-json\/wp\/v2\/tribe_events\/4502\/revisions"}],"predecessor-version":[{"id":4734,"href":"https:\/\/www.montanhismo-guarda.pt\/portal\/wp-json\/wp\/v2\/tribe_events\/4502\/revisions\/4734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.montanhismo-guarda.pt\/portal\/wp-json\/wp\/v2\/media\/4722"}],"wp:attachment":[{"href":"https:\/\/www.montanhismo-guarda.pt\/portal\/wp-json\/wp\/v2\/media?parent=4502"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.montanhismo-guarda.pt\/portal\/wp-json\/wp\/v2\/tags?post=4502"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.montanhismo-guarda.pt\/portal\/wp-json\/wp\/v2\/tribe_events_cat?post=4502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}